  {"id":34857,"date":"2021-09-09T13:30:43","date_gmt":"2021-09-09T13:30:43","guid":{"rendered":"https:\/\/abic.wpengine.com\/grabacion-inmigracion-y-economia-de-houston\/"},"modified":"2021-12-03T21:10:05","modified_gmt":"2021-12-03T21:10:05","slug":"grabacion-inmigracion-y-economia-de-houston","status":"publish","type":"post","link":"https:\/\/abic.us\/es\/grabacion-inmigracion-y-economia-de-houston\/","title":{"rendered":"GRABACI\u00d3N: INMIGRACI\u00d3N Y ECONOM\u00cdA DE HOUSTON"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.youtube.com\/watch?v=yPL1OoflYvw\"><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1068\" src=\"https:\/\/abic.imgix.net\/assets\/Screen-Shot-2021-09-09-at-2.25.34-PM.png\" alt=\"\" class=\"wp-image-31516\"\/><\/a><\/figure>\n<h2 class=\"has-text-align-center wp-block-heading\"><a href=\"https:\/\/www.youtube.com\/watch?v=yPL1OoflYvw\">GRABACI\u00d3N<\/a> ENLAZADO AQU\u00cd<\/h2>\n\n<p class=\"wp-block-paragraph\"><strong>El alcalde de Houston, Sylvester Turner, y la representante lizzie Fletcher (D-TX), l\u00edderes empresariales y trabajadores inmigrantes del \u00e1rea de Houston promocionan las contribuciones econ\u00f3micas de los inmigrantes, instan al Congreso a aprobar soluciones de inmigraci\u00f3n de sentido com\u00fan<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\"><em>El llamado a la acci\u00f3n llega un d\u00eda antes de que los l\u00edderes del Senado den su defensa de la inclusi\u00f3n de las reformas migratorias en la reconciliaci\u00f3n presupuestaria a los parlamentarios<\/em><\/p>\n\n<p class=\"wp-block-paragraph\">Houston, TX &#8212; Hoy el alcalde de Houston, Sylvester Turner, y la representante lizzie Fletcher (D-TX) se unieron a los l\u00edderes empresariales del \u00e1rea de Houston y a un param\u00e9dico beneficiario de DACA para resaltar la dependencia de la regi\u00f3n de Houston de los inmigrantes como trabajadores y empresarios, y la urgente necesidad econ\u00f3mica de que el Congreso cree un camino hacia la ciudadan\u00eda para los Dreamers, los trabajadores agr\u00edcolas, los beneficiarios del Estatus de Protecci\u00f3n Temporal (TPS) y los trabajadores esenciales.  <br\/><br\/>Ayer, <a href=\"http:\/\/link.mediaoutreach.meltwater.com\/ls\/click?upn=Z5Ymh5668oJULeadT1vlWBSz-2BCbF4K1fJBcKeZbVhbWsOfgsk1wbAf4T1WTzU5EAYbJvbW5ci-2B1dDxAcSNOi4akPJpfvdudEY814jpz4FZDxLLXBkmN7m-2BlypDXkzikpDIye76bIpsi4KeBeNBILxg-3D-3DW9T5_FecpbG-2BWS5wVt-2BM0HlHeo8FQoPPh2t6tFjzC8yvuGABP0Mi-2BrTkeji1YUkBgmoETfIdmOzfwfYdqmIUtl2oLSo7OWhSZJ8dtXkOXcK9Ot1-2FdxuAD-2ByRc7Ejwcivdlcja7SnwgJgRLObrOhY5GWEoHN5hzrUJE2i6LqFuj-2FoSARNAcKj0hucXrzfgtsbm3-2BvU1cXkkbW6YfWz01ikixuEIyrSj8jlMAy6-2BbeHzwfru1hfxynxnJohELjFiezAR-2BUQS1SrkIeBG4DKzu9-2FeCJQ-2Btri0-2BF8nlIc-2F1ipvD1AXY9bD3Qs7n0UqmttXe1lxqNauEXONLGNH-2FK4-2FrFqPi3cuBSxyz1yfWG-2B-2Fiv05kRx7Ye9r71RcnFB-2FgfD3tHyLLot\" target=\"_blank\" rel=\"noreferrer noopener\">se filtr\u00f3 la noticia<\/a> de que este viernes 10 de septiembre, los dem\u00f3cratas del Senado har\u00e1n el caso para incluir un camino hacia la ciudadan\u00eda en la reconciliaci\u00f3n presupuestaria. El lunes 13 de septiembre, el Comit\u00e9 Judicial de la C\u00e1mara de Representantes comenzar\u00e1 a marcar el texto legislativo de los $ 107 mil millones asignados en la resoluci\u00f3n presupuestaria para un camino hacia la ciudadan\u00eda para millones de trabajadores inmigrantes.<br\/><br\/>\u00abLa reforma migratoria es una necesidad vital para la sostenibilidad continua y el crecimiento de la econom\u00eda de Houston. Sin inmigrantes, nuestra ciudad no puede seguir siendo la potencia econ\u00f3mica inimitable en la que se ha convertido Houston. Son una de las principales razones por las que personas de todo el pa\u00eds se est\u00e1n mudando a Houston y otras ciudades de Texas para encontrar trabajos bien remunerados\u00bb, dijo.  <strong>Alcalde de la Ciudad de Houston Sylvester Turner.<\/strong> \u00abEl crecimiento econ\u00f3mico de Houston en los pr\u00f3ximos a\u00f1os depender\u00e1 de los inmigrantes. Los sectores de construcci\u00f3n, servicios, salud y TI, por ejemplo, depender\u00e1n m\u00e1s de los inmigrantes para satisfacer las demandas laborales. Los inmigrantes han ayudado y est\u00e1n ayudando actualmente a construir esta ciudad a lo que es hoy, y ser\u00e1n la clave para la prosperidad de nuestra ciudad en el futuro. Houston es una metr\u00f3polis pr\u00f3spera que ha hecho contribuciones en energ\u00eda, ciencia, medicina e ingenier\u00eda. Ninguno de estos logros habr\u00eda sido posible sin la ayuda de los inmigrantes que vinieron aqu\u00ed para perseguir sus sue\u00f1os y construir un futuro mejor y m\u00e1s brillante para ellos y sus familias. El Congreso necesita promulgar una reforma migratoria\u00bb<br\/><br\/>El alcalde Turner estuvo acompa\u00f1ado por <strong>la congresista Lizzie Fletcher (D-TX),<\/strong> quien ha copatrocinado proyectos de ley con disposiciones que espera ver aprobadas en el pr\u00f3ximo proceso de reconciliaci\u00f3n presupuestaria.<br\/><br\/>\u00abComo representante de esta comunidad, copatroci\u00e9 y vot\u00e9 por HR 6, la Ley del Sue\u00f1o 91探花o y la Promesa, para proporcionar el estatus de residente permanente legal para los beneficiarios de DACA y TPS, y la C\u00e1mara de Representantes ha aprobado este proyecto de ley en este Congreso, as\u00ed como el anterior. La C\u00e1mara de Representantes tambi\u00e9n ha aprobado la Ley de Modernizaci\u00f3n de la Fuerza Laboral Agr\u00edcola de 2021 esta primavera. Y ahora tenemos la oportunidad ante nosotros de abordar estos importantes asuntos nuevamente en el Plan Reconstruir Mejor en el proceso de reconciliaci\u00f3n que actualmente se abre camino en el Congreso\u00bb, dijo.  <strong>Representante Fletcher.<\/strong> \u00abSobre este tema ante el Congreso, el mensaje de Houston es claro: es el momento. Ya es hora de que el Congreso act\u00fae para abordar nuestro sistema de inmigraci\u00f3n roto con soluciones pr\u00e1cticas y de manera bipartidista para abordar los muchos problemas y desaf\u00edos y aprovechar las oportunidades que significar\u00e1 hacerlo para nuestras comunidades y nuestro pa\u00eds\u00bb.<br\/><br\/>Al igual que muchas ciudades de todo el pa\u00eds, Houston enfrenta escasez de trabajadores. Al mismo tiempo, los <a href=\"http:\/\/link.mediaoutreach.meltwater.com\/ls\/click?upn=Z5Ymh5668oJULeadT1vlWNwpfK3wKmPL6fKtj-2B0-2Fx4rhTmVN1E7rd3-2F8mI-2FS5oM-2F1z62-2BDqNmLKG7d5KkY6Ga-2BF4XiFZRj-2F-2BVz-2FQS2R-2BpT4-3DAi6z_FecpbG-2BWS5wVt-2BM0HlHeo8FQoPPh2t6tFjzC8yvuGABP0Mi-2BrTkeji1YUkBgmoETfIdmOzfwfYdqmIUtl2oLSo7OWhSZJ8dtXkOXcK9Ot1-2FdxuAD-2ByRc7Ejwcivdlcja7SnwgJgRLObrOhY5GWEoHN5hzrUJE2i6LqFuj-2FoSARNAcKj0hucXrzfgtsbm3-2BvU1cXkkbW6YfWz01ikixuEI23QSyYHtbAxxlTYdepDwB43PfBjYp23Ghj-2BB3nmtFdRBrQybD5gV2qpQdw3VtYR2LQRw9oJsR7uy7eqqFGVYKtcqVNB0iDhtH3ZhAd2M9XDScICcUXG9TWcoytykeU4JEVKQUq4msFIek1w7HNvc7IgaKgWOhK0v2z6k6t03oAE\" target=\"_blank\" rel=\"noreferrer noopener\">586,000 trabajadores indocumentados<\/a> de la ciudad tienen un poder adquisitivo total de $ 9.8 mil millones y pagan $ 1.2 mil millones en impuestos anualmente. Aprobar soluciones de inmigraci\u00f3n de sentido com\u00fan es crucial para impulsar la econom\u00eda de Houston, crear empleos, aliviar la escasez de mano de obra y apoyar a las familias.<br\/><br\/>\u00abComo coalici\u00f3n bipartidista de 1200 CEOs y Empleadores, preferimos firmemente las soluciones bipartidistas, pero a pesar de muchas conversaciones positivas con 41 senadores republicanos, ninguno ha dado un paso adelante para copatrocinar proyectos de ley bipartidistas e independientes existentes como el Dream Act\u00bb, dijo.  <strong>Director de TBIC y Subdirector de Campa\u00f1a de ABIC Juan Carlos Cerda.<\/strong>  \u00abSi la reconciliaci\u00f3n avanza, agregar inmigraci\u00f3n es el \u00fanico veh\u00edculo a la vista. Una nueva encuesta muestra que el 67 por ciento de los estadounidenses apoyan la legalizaci\u00f3n, y es por eso que instamos al Congreso a incluirla en su proyecto de ley de reconciliaci\u00f3n\u00bb.  <br\/><br\/>Ayer, un grupo de los principales economistas de la naci\u00f3n <a href=\"http:\/\/link.mediaoutreach.meltwater.com\/ls\/click?upn=Z5Ymh5668oJULeadT1vlWDpgYMbPbsZr-2BNvbf3DpgKg9uvFZ22OTLcUaoqMDGQx4FpO4U2rSLuI-2FVu0lYzYu-2Fu5H-2FFFpfvEA-2BMva0vljzgU92-2FnX44GCxKpT0DsB-2FcWjShexsRUrflDvbljNOUofbQ-3D-3D7wWT_FecpbG-2BWS5wVt-2BM0HlHeo8FQoPPh2t6tFjzC8yvuGABP0Mi-2BrTkeji1YUkBgmoETfIdmOzfwfYdqmIUtl2oLSo7OWhSZJ8dtXkOXcK9Ot1-2FdxuAD-2ByRc7Ejwcivdlcja7SnwgJgRLObrOhY5GWEoHN5hzrUJE2i6LqFuj-2FoSARNAcKj0hucXrzfgtsbm3-2BvU1cXkkbW6YfWz01ikixuEI77KCd6zIciBEsN6YK-2FG5fHPhjij8B7rKydo2vE6xW1qr9oH4Cd8RZGCUo-2F-2BNWIYJUVTk2RsrucJD9jKJ2bYSxMEbkzZOGOQ-2B74jJyoKvMScnAueBRYvIm3BIuAmVrUxEqUDldZqS94-2FeYPVG9Fm4IfoIwnpmoRaKB-2FQpwJeslpn\" target=\"_blank\" rel=\"noreferrer noopener\">envi\u00f3<\/a> una carta a los l\u00edderes del Congreso instando a un camino hacia la ciudadan\u00eda a trav\u00e9s de la reconciliaci\u00f3n, argumentando que impulsar\u00eda la econom\u00eda de los Estados Unidos. En la carta, los economistas calculan que \u00abcrear un camino hacia la ciudadan\u00eda para los Dreamers, aquellos elegibles para TPS e inmigrantes indocumentados en ocupaciones esenciales, incluidos los trabajadores agr\u00edcolas, aumentar\u00eda el PIB de los Estados Unidos en $ 1.5 billones, aumentar\u00eda los salarios anuales de todos los trabajadores en $ 600 y crear\u00eda m\u00e1s de 400,000 nuevos empleos durante la pr\u00f3xima d\u00e9cada. Una nueva <a href=\"http:\/\/link.mediaoutreach.meltwater.com\/ls\/click?upn=pzpdy847t9dVsOg1sRJNGYFPNBg55o-2BdMPmGBXA6Eq1fvYD3iAYN-2BX2uItffdT9OnUYY6ZvSbYtS034ukKjIbrIcHEelYS6iEi2unKOV6b2Bo24-2FFF5LdsJfdMGCW-2FAfskvcuiMC2kvxeRsgnd8zNQ-3D-3DlkOm_FecpbG-2BWS5wVt-2BM0HlHeo8FQoPPh2t6tFjzC8yvuGABP0Mi-2BrTkeji1YUkBgmoETfIdmOzfwfYdqmIUtl2oLSo7OWhSZJ8dtXkOXcK9Ot1-2FdxuAD-2ByRc7Ejwcivdlcja7SnwgJgRLObrOhY5GWEoHN5hzrUJE2i6LqFuj-2FoSARNAcKj0hucXrzfgtsbm3-2BvU1cXkkbW6YfWz01ikixuEI-2BTQuNUIxl0ugy4wT-2FnbXzzc9ojEbf6DTIiSQ9W98-2FF4NjeHAyuJL59vCKWJIlbh6Cc6bcFZgB1YZgTYbgon0jGFJ9eE6Yrk6ZRm3umLa9Yl4aiWfX9cO1d5mbBtCbUA3zDbX4p6eaZ2HT-2BzzBGAqoaoxRlwEKTmY-2FPtyLxP1R8C\" target=\"_blank\" rel=\"noreferrer noopener\">encuesta<\/a> encontr\u00f3 que el apoyo del 67-26% a la legalizaci\u00f3n en la reconciliaci\u00f3n se extiende a trav\u00e9s de las l\u00edneas partidarias, con una intensidad fuertemente pro-inmigrante.<br\/><br\/><strong>Otros comentarios de los oradores incluyeron:<\/strong><br\/><br\/><strong>Stan Marek, CEO, Marek Family of Companies:<\/strong>  \u00abSoy un empleador de trabajadores de la construcci\u00f3n&#8230; y nunca hemos tenido una escasez de mano de obra en mis cincuenta a\u00f1os como estamos viendo en este momento. Damas y caballeros, estamos perdiendo una oportunidad de oro para llevar a estos ni\u00f1os que vinieron sin causa propia, y no pueden conseguir un trabajo &#8230; Muchas de las personas en nuestra industria quieren reclutar de las escuelas secundarias, pero si el 30 o 40 por ciento son indocumentados, no lo van a hacer. Necesitamos un estatus legal para los ni\u00f1os que salen de la escuela secundaria para que puedan ingresar a un oficio y obtener un trabajo bueno y leg\u00edtimo y pagar impuestos\u00bb.<br\/><br\/><strong>Dra. Laura G. Murillo, CEO, C\u00e1mara de Comercio Hispana de Houston:<\/strong>  \u00abEstoy ante ustedes, ahora dirigiendo una de las c\u00e1maras de comercio m\u00e1s influyentes, porque a mis padres inmigrantes se les dio la oportunidad de prosperar y tener \u00e9xito. Trabajaron duro como lo han hecho muchos otros inmigrantes en este pa\u00eds, y en particular, en nuestra ciudad. Esta conversaci\u00f3n es sobre negocios: el impacto econ\u00f3mico que los inmigrantes hacen, han hecho y seguir\u00e1n teniendo en nuestra regi\u00f3n y en todo el pa\u00eds, los miles de millones de d\u00f3lares que contribuyen a nuestra base impositiva y tambi\u00e9n su gasto de consumo en nuestra regi\u00f3n y en todo el pa\u00eds. Este es el momento de actuar. Cada emprendedor, cada negocio con el que me conecto me dice que necesitan m\u00e1s trabajadores. No pueden contratar a suficientes personas. Si queremos que nuestra econom\u00eda siga siendo fuerte, debemos hacer de esto una prioridad, un imperativo econ\u00f3mico. Congreso, por favor act\u00fae. Hagamos lo correcto. Mantengamos a nuestro pa\u00eds econ\u00f3micamente vibrante y fuerte\u00bb.<br\/><br\/><strong>Jes\u00fas Contreras, beneficiario de DACA y param\u00e9dico:<\/strong>  \u00abYo era uno de esos estudiantes de secundaria que ten\u00edan la afortunada habilidad de aprobar un programa de comercio. La m\u00eda era la escuela EMT ofrecida a trav\u00e9s de Lonestar College. A pesar de que aprob\u00e9 el programa, no pude convertirme en un EMT certificado b\u00e1sicamente porque era indocumentado. Avanzando r\u00e1pidamente hasta 2013, la administraci\u00f3n Obama aprob\u00f3 DACA y pude perseguir mi sue\u00f1o de convertirme en param\u00e9dico. Poco despu\u00e9s de eso, estuve involucrado en los esfuerzos de rescate del hurac\u00e1n Harvey, la congelaci\u00f3n de febrero, algunas de las inundaciones del D\u00eda de los Impuestos y diferentes emergencias que han ocurrido aqu\u00ed en Houston. Hoy estoy trabajando en la primera l\u00ednea de la pandemia de Covid-19 y las personas que ha infectado. Una lucha que estoy viendo es que tenemos una escasez de EMT, param\u00e9dicos y personal de atenci\u00f3n m\u00e9dica. Muchos de nosotros somos beneficiarios de DACA. Muchos de nosotros somos titulares de TPS e inmigrantes. Qui\u00e9n sabe qui\u00e9n va a tomar ese lugar en la ambulancia si me deportan. Insto al Congreso a finalizar este proyecto de ley, para que se incluya una reforma migratoria integral en este proyecto de ley\u00bb.<br\/><\/p>\n\n<p class=\"wp-block-paragraph\"><strong>ACERCA DE  <\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">La<a href=\"http:\/\/link.mediaoutreach.meltwater.com\/ls\/click?upn=Z5Ymh5668oJULeadT1vlWH0ArQy-2B0l7fJupBT-2FXjbMI-3Dkqqp_FecpbG-2BWS5wVt-2BM0HlHeo8FQoPPh2t6tFjzC8yvuGABP0Mi-2BrTkeji1YUkBgmoETfIdmOzfwfYdqmIUtl2oLSo7OWhSZJ8dtXkOXcK9Ot1-2FdxuAD-2ByRc7Ejwcivdlcja7SnwgJgRLObrOhY5GWEoHN5hzrUJE2i6LqFuj-2FoSARNAcKj0hucXrzfgtsbm3-2BvU1cXkkbW6YfWz01ikixuEI7jPPFydzxl02M4wafWx98e4GXvbLrHS0lDMWAheyFv-2BKgDZw1homYDVkuM3dgzap-2FkqWFR41OLVy6jNG0i1muu3JEXxbyBAqKllRumXeZkyEzxWiiPBJicaXIPbaCvVsuPyoddMUlQ-2F9MygTeXD0Zi53KMdDGLLzWO-2BMWMsfPKh\" target=\"_blank\" rel=\"noreferrer noopener\"> 91探花 (ABIC)<\/a> promueve una reforma migratoria de sentido com\u00fan que promueve la competitividad econ\u00f3mica, proporciona a las empresas tanto el talento altamente calificado como el poco calificado que necesitan, y permite la integraci\u00f3n de los inmigrantes en nuestra econom\u00eda como consumidores, trabajadores, empresarios y ciudadanos. ABIC est\u00e1 activo en estados y comunidades clave de todo el pa\u00eds involucrando a activistas, defensores, l\u00edderes empresariales y funcionarios electos sobre la urgencia de aprobar una reforma migratoria que impulse nuestra econom\u00eda, cree empleos, alivie la escasez de mano de obra y apoye a las familias.  <\/p>\n\n<p class=\"wp-block-paragraph\">###<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GRABACI\u00d3N ENLAZADO AQU\u00cd El alcalde de Houston, Sylvester Turner, y la representante lizzie Fletcher (D-TX), l\u00edderes empresariales y trabajadores inmigrantes del \u00e1rea de Houston promocionan las contribuciones econ\u00f3micas de los&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63],"tags":[],"class_list":["post-34857","post","type-post","status-publish","format-standard","category-actualizaciones"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GRABACI\u00d3N: INMIGRACI\u00d3N Y ECONOM\u00cdA DE HOUSTON &#8212; Coalici\u00f3n 91探花a de Inmigraci\u00f3n Empresarial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abic.us\/es\/grabacion-inmigracion-y-economia-de-houston\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GRABACI\u00d3N: INMIGRACI\u00d3N Y ECONOM\u00cdA DE HOUSTON &#8212; Coalici\u00f3n 91探花a de Inmigraci\u00f3n Empresarial\" \/>\n<meta property=\"og:description\" content=\"GRABACI\u00d3N ENLAZADO AQU\u00cd El alcalde de Houston, Sylvester Turner, y la representante lizzie Fletcher (D-TX), l\u00edderes empresariales y trabajadores inmigrantes del \u00e1rea de Houston promocionan las contribuciones econ\u00f3micas de los...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abic.us\/es\/grabacion-inmigracion-y-economia-de-houston\/\" \/>\n<meta property=\"og:site_name\" content=\"Coalici\u00f3n 91探花a de Inmigraci\u00f3n Empresarial\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/91探花BIC\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-09T13:30:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-03T21:10:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/abic.imgix.net\/assets\/Screen-Shot-2021-09-09-at-2.25.34-PM.png\" \/>\n<meta name=\"author\" content=\"abic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@91探花BIC\" \/>\n<meta name=\"twitter:site\" content=\"@91探花BIC\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"abic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/abic.us\\\/es\\\/grabacion-inmigracion-y-economia-de-houston\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/abic.us\\\/es\\\/grabacion-inmigracion-y-economia-de-houston\\\/\"},\"author\":{\"name\":\"abic\",\"@id\":\"https:\\\/\\\/abic.us\\\/es\\\/#\\\/schema\\\/person\\\/58547098a0d3b973c110fd8a36f0e0bb\"},\"headline\":\"GRABACI\u00d3N: INMIGRACI\u00d3N Y ECONOM\u00cdA DE HOUSTON\",\"datePublished\":\"2021-09-09T13:30:43+00:00\",\"dateModified\":\"2021-12-03T21:10:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/abic.us\\\/es\\\/grabacion-inmigracion-y-economia-de-houston\\\/\"},\"wordCount\":1630,\"publisher\":{\"@id\":\"https:\\\/\\\/abic.us\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/abic.us\\\/es\\\/grabacion-inmigracion-y-economia-de-houston\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/abic.imgix.net\\\/assets\\\/Screen-Shot-2021-09-09-at-2.25.34-PM.png\",\"articleSection\":[\"Actualizaciones\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/abic.us\\\/es\\\/grabacion-inmigracion-y-economia-de-houston\\\/\",\"url\":\"https:\\\/\\\/abic.us\\\/es\\\/grabacion-inmigracion-y-economia-de-houston\\\/\",\"name\":\"GRABACI\u00d3N: INMIGRACI\u00d3N Y ECONOM\u00cdA DE HOUSTON &#8212; Coalici\u00f3n 91探花a de Inmigraci\u00f3n Empresarial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/abic.us\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/abic.us\\\/es\\\/grabacion-inmigracion-y-economia-de-houston\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/abic.us\\\/es\\\/grabacion-inmigracion-y-economia-de-houston\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/abic.imgix.net\\\/assets\\\/Screen-Shot-2021-09-09-at-2.25.34-PM.png\",\"datePublished\":\"2021-09-09T13:30:43+00:00\",\"dateModified\":\"2021-12-03T21:10:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/abic.us\\\/es\\\/grabacion-inmigracion-y-economia-de-houston\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/abic.us\\\/es\\\/grabacion-inmigracion-y-economia-de-houston\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/abic.us\\\/es\\\/grabacion-inmigracion-y-economia-de-houston\\\/#primaryimage\",\"url\":\"https:\\\/\\\/abic.imgix.net\\\/assets\\\/Screen-Shot-2021-09-09-at-2.25.34-PM.png\",\"contentUrl\":\"https:\\\/\\\/abic.imgix.net\\\/assets\\\/Screen-Shot-2021-09-09-at-2.25.34-PM.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/abic.us\\\/es\\\/grabacion-inmigracion-y-economia-de-houston\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hogar\",\"item\":\"https:\\\/\\\/abic.us\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GRABACI\u00d3N: INMIGRACI\u00d3N Y ECONOM\u00cdA DE HOUSTON\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/abic.us\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/abic.us\\\/es\\\/\",\"name\":\"Coalici\u00f3n 91探花a de Inmigraci\u00f3n Empresarial\",\"description\":\"Juntos, promoveremos una reforma migratoria sensata que crezca empleos, fortalezca nuestra econom\u00eda y beneficie a todas las familias estadounidenses.\",\"publisher\":{\"@id\":\"https:\\\/\\\/abic.us\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/abic.us\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/abic.us\\\/es\\\/#organization\",\"name\":\"91探花\",\"url\":\"https:\\\/\\\/abic.us\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/abic.us\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/abic.us\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/ABIC-Logo.png\",\"contentUrl\":\"https:\\\/\\\/abic.us\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/ABIC-Logo.png\",\"width\":1000,\"height\":260,\"caption\":\"91探花\"},\"image\":{\"@id\":\"https:\\\/\\\/abic.us\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/91探花BIC\",\"https:\\\/\\\/x.com\\\/91探花BIC\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/abic.us\\\/es\\\/#\\\/schema\\\/person\\\/58547098a0d3b973c110fd8a36f0e0bb\",\"name\":\"abic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a2893b0ce0ce34781c1e0a9251ffe4322e67c4e95cdf48463d10701c3bd4c8e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a2893b0ce0ce34781c1e0a9251ffe4322e67c4e95cdf48463d10701c3bd4c8e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a2893b0ce0ce34781c1e0a9251ffe4322e67c4e95cdf48463d10701c3bd4c8e?s=96&d=mm&r=g\",\"caption\":\"abic\"},\"sameAs\":[\"https:\\\/\\\/abic.wpengine.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GRABACI\u00d3N: INMIGRACI\u00d3N Y ECONOM\u00cdA DE HOUSTON &#8212; Coalici\u00f3n 91探花a de Inmigraci\u00f3n Empresarial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abic.us\/es\/grabacion-inmigracion-y-economia-de-houston\/","og_locale":"es_ES","og_type":"article","og_title":"GRABACI\u00d3N: INMIGRACI\u00d3N Y ECONOM\u00cdA DE HOUSTON &#8212; Coalici\u00f3n 91探花a de Inmigraci\u00f3n Empresarial","og_description":"GRABACI\u00d3N ENLAZADO AQU\u00cd El alcalde de Houston, Sylvester Turner, y la representante lizzie Fletcher (D-TX), l\u00edderes empresariales y trabajadores inmigrantes del \u00e1rea de Houston promocionan las contribuciones econ\u00f3micas de los...","og_url":"https:\/\/abic.us\/es\/grabacion-inmigracion-y-economia-de-houston\/","og_site_name":"Coalici\u00f3n 91探花a de Inmigraci\u00f3n Empresarial","article_publisher":"https:\/\/www.facebook.com\/91探花BIC","article_published_time":"2021-09-09T13:30:43+00:00","article_modified_time":"2021-12-03T21:10:05+00:00","og_image":[{"url":"https:\/\/abic.imgix.net\/assets\/Screen-Shot-2021-09-09-at-2.25.34-PM.png","type":"","width":"","height":""}],"author":"abic","twitter_card":"summary_large_image","twitter_creator":"@91探花BIC","twitter_site":"@91探花BIC","twitter_misc":{"Escrito por":"abic","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/abic.us\/es\/grabacion-inmigracion-y-economia-de-houston\/#article","isPartOf":{"@id":"https:\/\/abic.us\/es\/grabacion-inmigracion-y-economia-de-houston\/"},"author":{"name":"abic","@id":"https:\/\/abic.us\/es\/#\/schema\/person\/58547098a0d3b973c110fd8a36f0e0bb"},"headline":"GRABACI\u00d3N: INMIGRACI\u00d3N Y ECONOM\u00cdA DE HOUSTON","datePublished":"2021-09-09T13:30:43+00:00","dateModified":"2021-12-03T21:10:05+00:00","mainEntityOfPage":{"@id":"https:\/\/abic.us\/es\/grabacion-inmigracion-y-economia-de-houston\/"},"wordCount":1630,"publisher":{"@id":"https:\/\/abic.us\/es\/#organization"},"image":{"@id":"https:\/\/abic.us\/es\/grabacion-inmigracion-y-economia-de-houston\/#primaryimage"},"thumbnailUrl":"https:\/\/abic.imgix.net\/assets\/Screen-Shot-2021-09-09-at-2.25.34-PM.png","articleSection":["Actualizaciones"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/abic.us\/es\/grabacion-inmigracion-y-economia-de-houston\/","url":"https:\/\/abic.us\/es\/grabacion-inmigracion-y-economia-de-houston\/","name":"GRABACI\u00d3N: INMIGRACI\u00d3N Y ECONOM\u00cdA DE HOUSTON &#8212; Coalici\u00f3n 91探花a de Inmigraci\u00f3n Empresarial","isPartOf":{"@id":"https:\/\/abic.us\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/abic.us\/es\/grabacion-inmigracion-y-economia-de-houston\/#primaryimage"},"image":{"@id":"https:\/\/abic.us\/es\/grabacion-inmigracion-y-economia-de-houston\/#primaryimage"},"thumbnailUrl":"https:\/\/abic.imgix.net\/assets\/Screen-Shot-2021-09-09-at-2.25.34-PM.png","datePublished":"2021-09-09T13:30:43+00:00","dateModified":"2021-12-03T21:10:05+00:00","breadcrumb":{"@id":"https:\/\/abic.us\/es\/grabacion-inmigracion-y-economia-de-houston\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abic.us\/es\/grabacion-inmigracion-y-economia-de-houston\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/abic.us\/es\/grabacion-inmigracion-y-economia-de-houston\/#primaryimage","url":"https:\/\/abic.imgix.net\/assets\/Screen-Shot-2021-09-09-at-2.25.34-PM.png","contentUrl":"https:\/\/abic.imgix.net\/assets\/Screen-Shot-2021-09-09-at-2.25.34-PM.png"},{"@type":"BreadcrumbList","@id":"https:\/\/abic.us\/es\/grabacion-inmigracion-y-economia-de-houston\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hogar","item":"https:\/\/abic.us\/es\/"},{"@type":"ListItem","position":2,"name":"GRABACI\u00d3N: INMIGRACI\u00d3N Y ECONOM\u00cdA DE HOUSTON"}]},{"@type":"WebSite","@id":"https:\/\/abic.us\/es\/#website","url":"https:\/\/abic.us\/es\/","name":"Coalici\u00f3n 91探花a de Inmigraci\u00f3n Empresarial","description":"Juntos, promoveremos una reforma migratoria sensata que crezca empleos, fortalezca nuestra econom\u00eda y beneficie a todas las familias estadounidenses.","publisher":{"@id":"https:\/\/abic.us\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abic.us\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/abic.us\/es\/#organization","name":"91探花","url":"https:\/\/abic.us\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/abic.us\/es\/#\/schema\/logo\/image\/","url":"https:\/\/abic.us\/wp-content\/uploads\/2021\/11\/ABIC-Logo.png","contentUrl":"https:\/\/abic.us\/wp-content\/uploads\/2021\/11\/ABIC-Logo.png","width":1000,"height":260,"caption":"91探花"},"image":{"@id":"https:\/\/abic.us\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/91探花BIC","https:\/\/x.com\/91探花BIC"]},{"@type":"Person","@id":"https:\/\/abic.us\/es\/#\/schema\/person\/58547098a0d3b973c110fd8a36f0e0bb","name":"abic","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4a2893b0ce0ce34781c1e0a9251ffe4322e67c4e95cdf48463d10701c3bd4c8e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4a2893b0ce0ce34781c1e0a9251ffe4322e67c4e95cdf48463d10701c3bd4c8e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4a2893b0ce0ce34781c1e0a9251ffe4322e67c4e95cdf48463d10701c3bd4c8e?s=96&d=mm&r=g","caption":"abic"},"sameAs":["https:\/\/abic.wpengine.com"]}]}},"_links":{"self":[{"href":"https:\/\/abic.us\/es\/wp-json\/wp\/v2\/posts\/34857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abic.us\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/abic.us\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/abic.us\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/abic.us\/es\/wp-json\/wp\/v2\/comments?post=34857"}],"version-history":[{"count":0,"href":"https:\/\/abic.us\/es\/wp-json\/wp\/v2\/posts\/34857\/revisions"}],"wp:attachment":[{"href":"https:\/\/abic.us\/es\/wp-json\/wp\/v2\/media?parent=34857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abic.us\/es\/wp-json\/wp\/v2\/categories?post=34857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abic.us\/es\/wp-json\/wp\/v2\/tags?post=34857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}